{"id":2979,"date":"2024-08-15T16:26:28","date_gmt":"2024-08-15T16:26:28","guid":{"rendered":"https:\/\/sport-agency.it\/?page_id=2979"},"modified":"2024-08-22T09:10:59","modified_gmt":"2024-08-22T09:10:59","slug":"cookies","status":"publish","type":"page","link":"https:\/\/sport-agency.it\/it\/cookies\/","title":{"rendered":"Cookie-Richtlinie"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"2979\" class=\"elementor elementor-2979\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"e-con-top elementor-element elementor-element-ab7d2ba e-flex e-con-boxed e-con e-parent\" data-id=\"ab7d2ba\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-de61af0 elementor-widget elementor-widget-heading\" data-id=\"de61af0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Cookies<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9150be2 elementor-widget elementor-widget-spacer\" data-id=\"9150be2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-83e14bb e-con-full e-flex e-con e-child\" data-id=\"83e14bb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f95955c e-con-full e-flex e-con e-child\" data-id=\"f95955c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e1d2bc elementor-widget elementor-widget-text-editor\" data-id=\"1e1d2bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\n<!-- Legal document generated by Complianz | GDPR\/CCPA Cookie Consent https:\/\/wordpress.org\/plugins\/complianz-gdpr -->\n<div id=\"cmplz-document\" class=\"cmplz-document cookie-statement cmplz-document-eu\"><p><i>Questa politica sui cookie \u00e8 stata aggiornata l&#8217;ultima volta il Marzo 30, 2026 e si applica ai cittadini e ai residenti permanenti legali dello Spazio Economico Europeo e della Svizzera.<\/i><br><\/p><h2>1. Introduzione<\/h2><p>Il nostro sito web,<a href=\"https:\/\/sport-agency.it\/it\">https:\/\/sport-agency.it\/it<\/a> (di seguito: &#8222;il sito web&#8220;) utilizza i cookie e altre tecnologie correlate (per comodit\u00e0 tutte le tecnologie sono definite &#8222;cookie&#8220;). I cookie vengono anche inseriti da terze parti che abbiamo ingaggiato. Nel documento sottostante ti informiamo sull&#8217;uso dei cookie sul nostro sito web.<\/p><h2>2. Cosa sono i cookie?<\/h2><p>I cookie sono dei semplici file spediti assieme alle pagine di questo sito e salvati dal tuo browser sul disco rigido del tuo computer o altri dispositivi. Le informazioni raccolte in essi possono venire rispediti ai nostri server oppure ai server di terze parti durante la prossima visita.<\/p><h2>3. Cosa sono gli script?<\/h2><p>Uno script \u00e8 un pezzo di codice usato per far funzionare correttamente ed interattivamente il nostro sito. Questo codice viene eseguito sui nostri server o sul tuo dispositivo.<\/p><h2>4. Cos&#039;\u00e8 un web beacon?<\/h2><p>Un web beacon (o pixel tag) \u00e8 un piccolo, invisibile pezzo di testo o immagine su un sito che viene usato per monitorare il traffico di un sito web. Per fare questo, diversi dati su di te vengono conservati utilizzando dei web beacon.<\/p><h2>5. Cookie<\/h2><p class=\"cmplz-subtitle\">5.1 Cookie tecnici o funzionali<\/p><p>Alcuni cookie assicurano il corretto funzionamento del sito e che le tue preferenze rimangano valide. Piazzando cookie funzionali, rendiamo pi\u00f9 facile per te visitare il nostro sito web. In questo modo non devi inserire ripetutamente le stesse informazioni quando visiti il nostro sito web, per esempio, l&#8217;oggetto rimane nel tuo carrello finch\u00e9 non hai pagato. Possiamo piazzare questi cookie senza il tuo consenso.<\/p><p class=\"cmplz-subtitle\">5.2 Cookie statistici<\/p><p>Utilizziamo i cookie statistici per ottimizzare l&#8217;esperienza del sito web per i nostri utenti. Con questi cookie statistici otteniamo approfondimenti sull&#8217;uso del nostro sito web.&nbsp;Chiediamo il tuo permesso per piazzare cookie statistici.<\/p><p class=\"cmplz-subtitle\">5.3 Cookie di marketing\/tracciamento<\/p><p>I cookie di marketing\/tracciamento sono cookie o qualsiasi altra forma di memorizzazione locale, utilizzati per creare profili utente per visualizzare pubblicit\u00e0 o per tracciare l&#8217;utente su questo sito web o su diversi siti web per scopi di marketing simili.<\/p><h2>6. Cookie presenti<\/h2><div id=\"cmplz-cookies-overview\"><details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Elementor<\/h3>\n\t\t<p>Statistiche (anonimo)<\/p>\n\t\t<label for=\"cmplz_service_elementor\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service elementor<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_elementor\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"elementor\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo Elementor per creazione di contenuti. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/elementor\/\">Altro<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Questi dati non sono condivisi con terze parti.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Statistiche (anonimo)<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/elementor\/elementor\/\">elementor<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare le azioni compiute dall&#8217;utente sul sito web<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Complianz<\/h3>\n\t\t<p>Funzionale<\/p>\n\t\t<label for=\"cmplz_service_complianz\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service complianz<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_complianz\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"complianz\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo Complianz per gestione del consenso ai cookie. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/complianz\/\">Altro<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Questi dati non sono condivisi con terze parti.&nbsp;Per ulteriori informazioni, si prega di leggere <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/complianz.io\/legal\/privacy-statement\/\">Complianz Dichiarazione sulla Privacy<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funzionale<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_user_data\/\">cmplz_user_data<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Determina quale banner dei cookie mostrare<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_consented_services\/\">cmplz_consented_services<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare le preferenze del consenso ai cookie<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_policy_id\/\">cmplz_policy_id<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Registrare l&#8217;ID della cookie policy accettata<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_marketing\/\">cmplz_marketing<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare le preferenze del consenso ai cookie<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_statistics\/\">cmplz_statistics<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare le preferenze del consenso ai cookie<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_preferences\/\">cmplz_preferences<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare le preferenze del consenso ai cookie<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_functional\/\">cmplz_functional<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare le preferenze del consenso ai cookie<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_banner-status\/\">cmplz_banner-status<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Store if the cookie banner has been dismissed<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WordPress<\/h3>\n\t\t<p>Funzionale<\/p>\n\t\t<label for=\"cmplz_service_wordpress\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service wordpress<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wordpress\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wordpress\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo WordPress per sviluppo del sito web. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/wordpress\/\">Altro<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Questi dati non sono condivisi con terze parti.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funzionale<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wordpress_test_cookie\/\">wordpress_test_cookie<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">sessione<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Controlla se i cookie possono essere piazzati<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp_lang\/\">wp_lang<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">sessione<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare le impostazioni della lingua<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp-settings\/\">wp-settings-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare le preferenze utente<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp-settings-time\/\">wp-settings-time-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">1 anno<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare le preferenze utente<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wordpress_logged_in_\/\">wordpress_logged_in_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Mantieni l&#039;accesso degli utenti<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wpemojisettingssupports\/\">wpEmojiSettingsSupports<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">sessione<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare i dettagli del browser<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Analytics<\/h3>\n\t\t<p>Statistiche<\/p>\n\t\t<label for=\"cmplz_service_google-analytics\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-analytics<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-analytics\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-analytics\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo Google Analytics per statistiche del sito web. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-analytics\/\">Altro<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Per ulteriori informazioni, si prega di leggere <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/business.safety.google\/privacy\/\">Google Analytics Dichiarazione sulla Privacy<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Statistiche<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-analytics\/_ga\/\">_ga<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">2 anni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Conta e traccia le visualizzazioni delle pagine<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-analytics\/_ga_\/\">_ga_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">1 anno<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Conta e traccia le visualizzazioni delle pagine<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Wistia<\/h3>\n\t\t<p>Statistiche, Pubblicit\u00e0<\/p>\n\t\t<label for=\"cmplz_service_wistia\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service wistia<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wistia\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wistia\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo Wistia per mostrare video. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/wistia\/\">Altro<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Per ulteriori informazioni, si prega di leggere <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/wistia.com\/privacy\">Wistia Dichiarazione sulla Privacy<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Statistiche<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wistia\/wistia-video-progress\/\">wistia-video-progress-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare se l&#039;utente ha visto un contenuto incorporato<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Pubblicit\u00e0<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wistia\/wistia\/\">wistia<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare le azioni compiute dall&#8217;utente sul sito web<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Adobe Fonts<\/h3>\n\t\t<p>Pubblicit\u00e0<\/p>\n\t\t<label for=\"cmplz_service_adobe-fonts\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service adobe-fonts<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_adobe-fonts\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"adobe-fonts\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo Adobe Fonts per mostrare i webfont. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/adobefonts\/\">Altro<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Per ulteriori informazioni, si prega di leggere <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.adobe.com\/privacy\/policies\/adobe-fonts.html\">Adobe Fonts Dichiarazione sulla Privacy<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Pubblicit\u00e0<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/adobefonts\/adobefonts\/\">Adobe Fonts API<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">nessuno<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Richiedere l&#8217;indirizzo IP dell&#8217;utente<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Fonts<\/h3>\n\t\t<p>Pubblicit\u00e0<\/p>\n\t\t<label for=\"cmplz_service_google-fonts\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-fonts<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-fonts\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-fonts\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo Google Fonts per mostrare i webfont. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-fonts\/\">Altro<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Per ulteriori informazioni, si prega di leggere <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">Google Fonts Dichiarazione sulla Privacy<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Pubblicit\u00e0<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-fonts\/tcb_google_fonts\/\">Google Fonts API<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">nessuno<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Richiedere l&#8217;indirizzo IP dell&#8217;utente<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google reCAPTCHA<\/h3>\n\t\t<p>Pubblicit\u00e0<\/p>\n\t\t<label for=\"cmplz_service_google-recaptcha\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-recaptcha<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-recaptcha\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-recaptcha\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo Google reCAPTCHA per prevenzione dello spam. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-recaptcha\/\">Altro<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Per ulteriori informazioni, si prega di leggere <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">Google reCAPTCHA Dichiarazione sulla Privacy<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Pubblicit\u00e0<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-recaptcha\/rcc\/\">rc::c<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">sessione<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Filtra richieste dei bot<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-recaptcha\/rcb\/\">rc::b<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">sessione<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Filtra richieste dei bot<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-recaptcha\/rca\/\">rc::a<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Filtra richieste dei bot<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Maps<\/h3>\n\t\t<p>Pubblicit\u00e0<\/p>\n\t\t<label for=\"cmplz_service_google-maps\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-maps<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-maps\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-maps\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo Google Maps per mappare i display. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-maps\/\">Altro<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Per ulteriori informazioni, si prega di leggere <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/business.safety.google\/privacy\/\">Google Maps Dichiarazione sulla Privacy<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Pubblicit\u00e0<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-maps\/google-maps-api\/\">Google Maps API<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">nessuno<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Richiedere l&#8217;indirizzo IP dell&#8217;utente<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Vimeo<\/h3>\n\t\t<p>Statistiche<\/p>\n\t\t<label for=\"cmplz_service_vimeo\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service vimeo<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_vimeo\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"vimeo\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo Vimeo per mostrare video. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/vimeo\/\">Altro<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Per ulteriori informazioni, si prega di leggere <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/vimeo.com\/privacy\">Vimeo Dichiarazione sulla Privacy<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Statistiche<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/vimeo\/__utmt_player\/\">__utmt_player<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">10 minuti<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare e tracciare la portata del pubblico<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/vimeo\/vuid\/\">vuid<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">2 anni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare la cronologia d&#039;utilizzo dell&#039;utente<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>YouTube<\/h3>\n\t\t<p>Pubblicit\u00e0<\/p>\n\t\t<label for=\"cmplz_service_youtube\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service youtube<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_youtube\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"youtube\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo YouTube per mostrare video. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/youtube\/\">Altro<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Per ulteriori informazioni, si prega di leggere <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">YouTube Dichiarazione sulla Privacy<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Pubblicit\u00e0<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/youtube\/gps\/\">GPS<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">sessione<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare i dati di posizione<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/youtube\/visitor_info1_live\/\">VISITOR_INFO1_LIVE<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">6 mesi<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Abilita consegna annunci o retargeting<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/youtube\/ysc\/\">YSC<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">sessione<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Interaktion speichern und verfolgen<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/youtube\/pref\/\">PREF<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">8 mesi<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare le preferenze utente<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy\">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Varie<\/h3>\n\t\t<p>Scopo in attesa di indagine<\/p>\n\t\t<label for=\"cmplz_service_varie\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service varie<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_varie\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"varie\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>La condivisione dei dati \u00e8 in attesa di indagine<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Scopo in attesa di indagine<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">e_kit-elements-defaults<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">loglevel<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">__3g4_session_id<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/perf_\/\">perf_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<\/div><h2>7. Consenti<\/h2><p>Quando visiti il sito web per la prima volta, noi mostreremo un popup con una spiegazione dei cookie. Appena clicchi su &#8222;Einstellungen speichern&#8220;, dai il permesso a noi di usare le categorie di cookie e plugin come descritto in questa dichiarazione relativa ai popup e cookie. Puoi disabilitare i cookie attraverso il tuo browser, ma prendi in considerazione, che il nostro sito web potrebbe non funzionare pi\u00f9 correttamente.<\/p><p class=\"cmplz-subtitle\">7.1 Gestisci le tue impostazioni di consenso<\/p><div id=\"cmplz-manage-consent-container-nojavascript\">Hai caricato la Cookie Policy senza supporto javascript.&nbsp;Su AMP, puoi usare il pulsante di gestione del consenso in fondo alla pagina.<\/div><div id=\"cmplz-manage-consent-container\" class=\"cmplz-manage-consent-container\"><\/div><h2>8. Abilitare\/disabilitare e cancellazione cookie<\/h2><p>Puoi usare il tuo browser per cancellare automaticamente o manualmente i cookie. \u00c8 anche possibile specificare che determinati cookie non possono essere piazzati. Un&#8217;altra opzione \u00e8 quella di modificare le impostazioni del tuo browser internet in modo da ricevere un messaggio ogni volta che viene inserito un cookie. Per ulteriori informazioni su queste opzioni, consultare le istruzioni nella sezione Guida del tuo browser.<\/p><p>Tieni presente che il nostro sito web potrebbe non funzionare correttamente se tutti i cookie sono disabilitati. Se cancelli i cookie nel vostro browser, essi verranno nuovamente inseriti dopo il consenso fornito quando visiterete nuovamente il nostro sito web.<\/p><h2>9. I tuoi diritti con rispetto ai dati personali<\/h2><p>Hai i seguenti diritti relativi ai tuoi dati personali:<\/p><ul>\n                    <li>Hai il diritto di sapere quando i tuoi dati personali sono necessari, cosa succede ad essi, quanto a lungo verranno mantenuti.<\/li>\n                    <li>Diritto di accesso: hai il diritto ad accedere ai tuoi dati personali dei quali siamo a conoscenza.<\/li>\n                    <li>Diritto di rettifica: hai il diritto di completare, correggere, cancellare o bloccare i tuoi dati personali quando lo desideri.<\/li>\n                    <li>Se ci darai il consenso per elaborare i tuoi dati, hai il diritto di revocare questo consenso e di eliminare i tuoi dati personali.<\/li>\n                    <li>Diritto di trasferire i tuoi dati: hai il diritto di richiedere tutti i tuoi dati dal controllore e trasferirli tutti quanti ad un altro controllore.<\/li>\n                    <li>Diritto di obiezione: hai il diritto di obiezione verso il processo dei tuoi dati. Noi rispetteremo questa scelta, a meno che non ci siano delle basi valide per il processo.<\/li>\n                <\/ul><p>Per esercitare questi diritti, non esitate a contattarci. Si prega di fare riferimento ai dettagli di contatto in fondo a questa Cookie Policy. Se hai un reclamo su come gestiamo i tuoi dati, vorremmo sentirti, ma hai anche il diritto di presentare un reclamo all&#8217;autorit\u00e0 di vigilanza (l&#8217;Autorit\u00e0 per la Protezione dei Dati).<\/p><h2>10. Dettagli contatti<\/h2><p>Per domande e\/o commenti riguardo la Cookie Policy e questa dichiarazione, per favore contattaci usando i seguenti dati di contatto:<\/p><p><span class=\"cmplz-contact-organisation\">Armin Sport Agency di Armin Forer<\/span><br>\n                      <span class=\"cmplz-contact-address\">Via Julius Durst Str. 44c<br \/>\n39042 Brixen<br \/>\nItalia<\/span><br>\n                      <span class=\"cmplz-contact-country\">Italia<\/span><br>\n                    Sito web: <span class=\"cmplz-contact-domain\"><a href=\"https:\/\/sport-agency.it\/it\">https:\/\/sport-agency.it\/it<\/a><\/span><br>\n                    Email: <span class=\"cmplz-contact-email\"><span class=\"cmplz-obfuscate\">&#105;nf&#111;@<span class=\"cmplz-fmail-domain\">ex.&#099;o&#109;<\/span>&#115;&#112;&#111;r&#116;-a&#103;enc&#121;&#046;it<\/span><\/span><br>\n                    <span class=\"cmplz-contact-telephone\">Numero di telefono: +39 329 050 6306<\/span><\/p><p>Questa politica sui cookie \u00e8 stata sincronizzata con <a href=\"https:\/\/cookiedatabase.org\/\" target=\"_blank\">cookiedatabase.org<\/a> il Agosto 27, 2026.<\/p><\/div><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-93158fe e-con-full e-flex e-con e-child\" data-id=\"93158fe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Cookies<\/p>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2979","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Cookies Questa politica sui cookie \u00e8 stata aggiornata l\u2019ultima volta il Marzo 30, 2026 e si applica ai cittadini e ai residenti permanenti legali dello Spazio Economico Europeo e della Svizzera.1. IntroduzioneIl nostro sito web,https:\/\/sport-agency.it\/it (di seguito: \u201eil sito web\u201c) utilizza i cookie e altre tecnologie correlate (per comodit\u00e0 tutte le tecnologie sono definite \u201ecookie\u201c).\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/sport-agency.it\/it\/cookies\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Armin Sport Agency -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Cookie-Richtlinie - Armin Sport Agency\" \/>\n\t\t<meta property=\"og:description\" content=\"Cookies Questa politica sui cookie \u00e8 stata aggiornata l\u2019ultima volta il Marzo 30, 2026 e si applica ai cittadini e ai residenti permanenti legali dello Spazio Economico Europeo e della Svizzera.1. IntroduzioneIl nostro sito web,https:\/\/sport-agency.it\/it (di seguito: \u201eil sito web\u201c) utilizza i cookie e altre tecnologie correlate (per comodit\u00e0 tutte le tecnologie sono definite \u201ecookie\u201c).\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/sport-agency.it\/it\/cookies\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/sport-agency.it\/wp-content\/uploads\/2024\/07\/logo-black.svg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/sport-agency.it\/wp-content\/uploads\/2024\/07\/logo-black.svg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"141\" \/>\n\t\t<meta property=\"og:image:height\" content=\"76\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-08-15T16:26:28+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-08-22T09:10:59+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Cookie-Richtlinie - Armin Sport Agency\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Cookies Questa politica sui cookie \u00e8 stata aggiornata l\u2019ultima volta il Marzo 30, 2026 e si applica ai cittadini e ai residenti permanenti legali dello Spazio Economico Europeo e della Svizzera.1. IntroduzioneIl nostro sito web,https:\/\/sport-agency.it\/it (di seguito: \u201eil sito web\u201c) utilizza i cookie e altre tecnologie correlate (per comodit\u00e0 tutte le tecnologie sono definite \u201ecookie\u201c).\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/sport-agency.it\/wp-content\/uploads\/2024\/07\/logo-black.svg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sport-agency.it\\\/it\\\/cookies\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sport-agency.it\\\/it#listItem\",\"position\":1,\"name\":\"Zu Hause\",\"item\":\"https:\\\/\\\/sport-agency.it\\\/it\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sport-agency.it\\\/it\\\/cookies\\\/#listItem\",\"name\":\"Cookie-Richtlinie\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sport-agency.it\\\/it\\\/cookies\\\/#listItem\",\"position\":2,\"name\":\"Cookie-Richtlinie\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sport-agency.it\\\/it#listItem\",\"name\":\"Zu Hause\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sport-agency.it\\\/it\\\/#organization\",\"name\":\"Armin Sport Agency\",\"url\":\"https:\\\/\\\/sport-agency.it\\\/it\\\/\",\"telephone\":\"+393290506306\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/sport-agency.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo-black.svg\",\"@id\":\"https:\\\/\\\/sport-agency.it\\\/it\\\/cookies\\\/#organizationLogo\",\"width\":141,\"height\":76},\"image\":{\"@id\":\"https:\\\/\\\/sport-agency.it\\\/it\\\/cookies\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/a_sportagency\\\/\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sport-agency.it\\\/it\\\/cookies\\\/#webpage\",\"url\":\"https:\\\/\\\/sport-agency.it\\\/it\\\/cookies\\\/\",\"name\":\"Cookie-Richtlinie - Armin Sport Agency\",\"description\":\"Cookies Questa politica sui cookie \\u00e8 stata aggiornata l\\u2019ultima volta il Marzo 30, 2026 e si applica ai cittadini e ai residenti permanenti legali dello Spazio Economico Europeo e della Svizzera.1. IntroduzioneIl nostro sito web,https:\\\/\\\/sport-agency.it\\\/it (di seguito: \\u201eil sito web\\u201c) utilizza i cookie e altre tecnologie correlate (per comodit\\u00e0 tutte le tecnologie sono definite \\u201ecookie\\u201c).\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sport-agency.it\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sport-agency.it\\\/it\\\/cookies\\\/#breadcrumblist\"},\"datePublished\":\"2024-08-15T16:26:28+00:00\",\"dateModified\":\"2024-08-22T09:10:59+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sport-agency.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/sport-agency.it\\\/it\\\/\",\"name\":\"- Armin Sport Agency\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/sport-agency.it\\\/it\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Cookie-Richtlinie - Armin Sport Agency","description":"Cookies Questa politica sui cookie \u00e8 stata aggiornata l\u2019ultima volta il Marzo 30, 2026 e si applica ai cittadini e ai residenti permanenti legali dello Spazio Economico Europeo e della Svizzera.1. IntroduzioneIl nostro sito web,https:\/\/sport-agency.it\/it (di seguito: \u201eil sito web\u201c) utilizza i cookie e altre tecnologie correlate (per comodit\u00e0 tutte le tecnologie sono definite \u201ecookie\u201c).","canonical_url":"https:\/\/sport-agency.it\/it\/cookies\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/sport-agency.it\/it\/cookies\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/sport-agency.it\/it#listItem","position":1,"name":"Zu Hause","item":"https:\/\/sport-agency.it\/it","nextItem":{"@type":"ListItem","@id":"https:\/\/sport-agency.it\/it\/cookies\/#listItem","name":"Cookie-Richtlinie"}},{"@type":"ListItem","@id":"https:\/\/sport-agency.it\/it\/cookies\/#listItem","position":2,"name":"Cookie-Richtlinie","previousItem":{"@type":"ListItem","@id":"https:\/\/sport-agency.it\/it#listItem","name":"Zu Hause"}}]},{"@type":"Organization","@id":"https:\/\/sport-agency.it\/it\/#organization","name":"Armin Sport Agency","url":"https:\/\/sport-agency.it\/it\/","telephone":"+393290506306","logo":{"@type":"ImageObject","url":"https:\/\/sport-agency.it\/wp-content\/uploads\/2024\/07\/logo-black.svg","@id":"https:\/\/sport-agency.it\/it\/cookies\/#organizationLogo","width":141,"height":76},"image":{"@id":"https:\/\/sport-agency.it\/it\/cookies\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/a_sportagency\/"]},{"@type":"WebPage","@id":"https:\/\/sport-agency.it\/it\/cookies\/#webpage","url":"https:\/\/sport-agency.it\/it\/cookies\/","name":"Cookie-Richtlinie - Armin Sport Agency","description":"Cookies Questa politica sui cookie \u00e8 stata aggiornata l\u2019ultima volta il Marzo 30, 2026 e si applica ai cittadini e ai residenti permanenti legali dello Spazio Economico Europeo e della Svizzera.1. IntroduzioneIl nostro sito web,https:\/\/sport-agency.it\/it (di seguito: \u201eil sito web\u201c) utilizza i cookie e altre tecnologie correlate (per comodit\u00e0 tutte le tecnologie sono definite \u201ecookie\u201c).","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/sport-agency.it\/it\/#website"},"breadcrumb":{"@id":"https:\/\/sport-agency.it\/it\/cookies\/#breadcrumblist"},"datePublished":"2024-08-15T16:26:28+00:00","dateModified":"2024-08-22T09:10:59+00:00"},{"@type":"WebSite","@id":"https:\/\/sport-agency.it\/it\/#website","url":"https:\/\/sport-agency.it\/it\/","name":"- Armin Sport Agency","inLanguage":"it-IT","publisher":{"@id":"https:\/\/sport-agency.it\/it\/#organization"}}]},"og:locale":"it_IT","og:site_name":"Armin Sport Agency -","og:type":"article","og:title":"Cookie-Richtlinie - Armin Sport Agency","og:description":"Cookies Questa politica sui cookie \u00e8 stata aggiornata l\u2019ultima volta il Marzo 30, 2026 e si applica ai cittadini e ai residenti permanenti legali dello Spazio Economico Europeo e della Svizzera.1. IntroduzioneIl nostro sito web,https:\/\/sport-agency.it\/it (di seguito: \u201eil sito web\u201c) utilizza i cookie e altre tecnologie correlate (per comodit\u00e0 tutte le tecnologie sono definite \u201ecookie\u201c).","og:url":"https:\/\/sport-agency.it\/it\/cookies\/","og:image":"https:\/\/sport-agency.it\/wp-content\/uploads\/2024\/07\/logo-black.svg","og:image:secure_url":"https:\/\/sport-agency.it\/wp-content\/uploads\/2024\/07\/logo-black.svg","og:image:width":141,"og:image:height":76,"article:published_time":"2024-08-15T16:26:28+00:00","article:modified_time":"2024-08-22T09:10:59+00:00","twitter:card":"summary_large_image","twitter:title":"Cookie-Richtlinie - Armin Sport Agency","twitter:description":"Cookies Questa politica sui cookie \u00e8 stata aggiornata l\u2019ultima volta il Marzo 30, 2026 e si applica ai cittadini e ai residenti permanenti legali dello Spazio Economico Europeo e della Svizzera.1. IntroduzioneIl nostro sito web,https:\/\/sport-agency.it\/it (di seguito: \u201eil sito web\u201c) utilizza i cookie e altre tecnologie correlate (per comodit\u00e0 tutte le tecnologie sono definite \u201ecookie\u201c).","twitter:image":"https:\/\/sport-agency.it\/wp-content\/uploads\/2024\/07\/logo-black.svg"},"aioseo_meta_data":{"post_id":"2979","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-08-16 07:47:54","updated":"2026-03-30 08:50:51","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/sport-agency.it\/it\" title=\"Zu Hause\">Zu Hause<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCookie-Richtlinie\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Zu Hause","link":"https:\/\/sport-agency.it\/it"},{"label":"Cookie-Richtlinie","link":"https:\/\/sport-agency.it\/it\/cookies\/"}],"acf":[],"_links":{"self":[{"href":"https:\/\/sport-agency.it\/it\/wp-json\/wp\/v2\/pages\/2979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sport-agency.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sport-agency.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sport-agency.it\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sport-agency.it\/it\/wp-json\/wp\/v2\/comments?post=2979"}],"version-history":[{"count":10,"href":"https:\/\/sport-agency.it\/it\/wp-json\/wp\/v2\/pages\/2979\/revisions"}],"predecessor-version":[{"id":3964,"href":"https:\/\/sport-agency.it\/it\/wp-json\/wp\/v2\/pages\/2979\/revisions\/3964"}],"wp:attachment":[{"href":"https:\/\/sport-agency.it\/it\/wp-json\/wp\/v2\/media?parent=2979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}